{"id":12491,"date":"2024-07-06T16:21:00","date_gmt":"2024-07-06T14:21:00","guid":{"rendered":"https:\/\/avante.pl\/?p=12491"},"modified":"2025-10-01T11:11:41","modified_gmt":"2025-10-01T09:11:41","slug":"lumaxx","status":"publish","type":"post","link":"https:\/\/avante.pl\/en\/lumaxx\/","title":{"rendered":"lumaxx"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12491\" class=\"elementor elementor-12491 elementor-12489\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7190c1df elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"7190c1df\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6b9294a0\" data-id=\"6b9294a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22249662 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"22249662\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/avante.pl\/oferta\/\">Offer \/ <\/a><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-206af545 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"206af545\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/avante.pl\/en\/category\/pvc-windows\/\" rel=\"tag\">PVC windows<\/a> \/<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b8cf686 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"6b8cf686\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">lumaxx<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33910e9a elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"33910e9a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-162e365d\" data-id=\"162e365d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1feeaefd elementor-flip-box--effect-fade elementor-hidden-mobile elementor-widget elementor-widget-flip-box\" data-id=\"1feeaefd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper elementor-view-default\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5c12d371\" data-id=\"5c12d371\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33ae63fb elementor-widget elementor-widget-heading\" data-id=\"33ae63fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">lumaxx<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48d46fec elementor-flip-box--effect-fade elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra elementor-widget elementor-widget-flip-box\" data-id=\"48d46fec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper elementor-view-default\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53ee6db8 elementor-widget elementor-widget-text-editor\" data-id=\"53ee6db8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex-shrink-0 flex flex-col relative items-end\"><div><div class=\"pt-0\"><div class=\"gizmo-bot-avatar flex h-8 w-8 items-center justify-center overflow-hidden rounded-full\"><div class=\"relative p-1 rounded-sm flex items-center justify-center bg-token-main-surface-primary text-token-text-primary h-8 w-8\">This is a modern window solution, distinguished by exceptionally slim profiles, much narrower than traditional constructions. Thanks to Lumaxx\u2019s innovative technology, the low assembly of the frame and sash allows for a sleek window appearance, while ensuring maximum light intake and excellent thermal insulation performance.<\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dea261e elementor-align-left elementor-mobile-align-left elementor-widget__width-auto elementor-widget-laptop__width-auto elementor-widget-tablet_extra__width-auto elementor-widget-tablet__width-auto elementor-widget elementor-widget-button\" data-id=\"7dea261e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/avante.pl\/wp-content\/uploads\/2025\/10\/ENG\/karta_techniczna_lumaxx_en.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Product card<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50c3590d elementor-align-left elementor-mobile-align-left elementor-widget__width-auto elementor-widget-laptop__width-auto elementor-widget-tablet_extra__width-auto elementor-widget-tablet__width-auto elementor-widget elementor-widget-button\" data-id=\"50c3590d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/avante.pl\/en\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contact us<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7408b2f7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7408b2f7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c9ac877\" data-id=\"c9ac877\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fbd78d8 elementor-widget elementor-widget-heading\" data-id=\"3fbd78d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Technical Specifications<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-315e810 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"315e810\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-54aca6ef\" data-id=\"54aca6ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-pafe-close-first-accordion=\"\" class=\"elementor-element elementor-element-68b3f52b elementor-widget elementor-widget-accordion\" data-id=\"68b3f52b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1751\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1751\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">thermal insulation<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1751\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1751\"><table>\n<tbody>\n<tr>\n<td>Uw coefficient<\/td>\n<td> 0,79 W\/m\u00b2K*<\/td>\n<\/tr>\n<tr>\n<td>glazing thickness<\/td>\n<td> up to 48 mm<\/td>\n<\/tr>\n<tr>\n<td>installation depth<\/td>\n<td> 82,5 mm<\/td>\n<\/tr>\n<tr>\n<td>6-chamber technology<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>*for the reference window 1230\u00d71480 mm with glass Ug = 0.5<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2c32224c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c32224c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1456c34e\" data-id=\"1456c34e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-pafe-close-first-accordion=\"\" class=\"elementor-element elementor-element-72026842 elementor-widget elementor-widget-accordion\" data-id=\"72026842\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1911\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1911\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">security<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1911\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1911\"><p>The enhanced static parameters of the structure ensure dimensional stability and resistance to deformation. The possibility of bonding glass using STV technology provides additional reinforcement for the window construction.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8687c06 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8687c06\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7c9f3c5e\" data-id=\"7c9f3c5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-pafe-close-first-accordion=\"\" class=\"elementor-element elementor-element-91817e9 elementor-widget elementor-widget-accordion\" data-id=\"91817e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1521\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1521\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">komfort<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1521\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1521\"><p>Comfortable use of Lumaxx windows is guaranteed by the use of top-quality fittings and window accessories. It is possible to equip windows with various types of window blinds or mosquito nets to protect against excessive heating of rooms and insect invasion. <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-55d98fb2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55d98fb2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-78acd12d\" data-id=\"78acd12d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-pafe-close-first-accordion=\"\" class=\"elementor-element elementor-element-3530bfd4 elementor-widget elementor-widget-accordion\" data-id=\"3530bfd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8921\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8921\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">design<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8921\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8921\"><p>in a classic version, it guarantees a good stylistic match to traditional and modern buildings. Possibility to choose from many color versions, from metallic, through wood-like, to smooth and structural colors imitating aluminum.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5699afef elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"5699afef\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c6433d4\" data-id=\"4c6433d4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b86343 elementor-widget elementor-widget-template\" data-id=\"4b86343\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"7014\" class=\"elementor elementor-7014 elementor-1943 elementor-1943\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-626c995f elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"626c995f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3bc21b3b\" data-id=\"3bc21b3b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f689757 elementor-widget elementor-widget-heading\" data-id=\"6f689757\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">color scheme<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20c3c9b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20c3c9b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-67a7304\" data-id=\"67a7304\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8dd9f99 elementor-widget elementor-widget-text-editor\" data-id=\"8dd9f99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>See what colors your new windows can be in. To enlarge, hover the cursor and click on the desired color. Please note that the colors you see may differ from the actual colors due to your monitor&#8217;s display settings.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6efdbf56 elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"6efdbf56\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-10 elementor-top-column elementor-element elementor-element-5c6ebecf\" data-id=\"5c6ebecf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-2d639e3a elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Anthracite 7016&lt;\\\/strong&gt;&lt;\\\/p&gt;&lt;p&gt;&lt;strong&gt;smooth&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"2d639e3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-2d639e3a\" class=\"jet-tooltip-widget__content\"><p><strong>Anthracite 7016<\/strong><\/p><p><strong>smooth<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/antracyt-RAL.png\" class=\"attachment-large size-large wp-image-8622\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/antracyt-RAL.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/antracyt-RAL-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-eb87def elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Realwood&lt;\\\/strong&gt;&lt;\\\/p&gt;&lt;p&gt;&lt;strong&gt;Woodec Turner oak&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:&quot;&quot;,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"eb87def\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-eb87def\" class=\"jet-tooltip-widget__content\"><p><strong>Realwood<\/strong><\/p><p><strong>Woodec Turner oak<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Realwood-woodec-Turner-oak.png\" class=\"attachment-large size-large wp-image-8913\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Realwood-woodec-Turner-oak.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Realwood-woodec-Turner-oak-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-a603c7d elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Realwood&lt;\\\/strong&gt;&lt;\\\/p&gt;&lt;p&gt;&lt;strong&gt;Ginger oak&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"a603c7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-a603c7d\" class=\"jet-tooltip-widget__content\"><p><strong>Realwood<\/strong><\/p><p><strong>Ginger oak<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Realwood-dab-imbirowy.png\" class=\"attachment-large size-large wp-image-8901\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Realwood-dab-imbirowy.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Realwood-dab-imbirowy-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-33c266e elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Realwood&lt;\\\/strong&gt;&lt;\\\/p&gt;&lt;p&gt;&lt;strong&gt;Honey oak&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"33c266e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-33c266e\" class=\"jet-tooltip-widget__content\"><p><strong>Realwood<\/strong><\/p><p><strong>Honey oak<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Realwood-dab-miodowy.png\" class=\"attachment-large size-large wp-image-8905\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Realwood-dab-miodowy.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Realwood-dab-miodowy-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-69ebe4d elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Platinum bronze&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"69ebe4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-69ebe4d\" class=\"jet-tooltip-widget__content\"><p><strong>Platinum bronze<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Braz-platynowy.png\" class=\"attachment-large size-large wp-image-8793\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Braz-platynowy.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Braz-platynowy-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-10 elementor-top-column elementor-element elementor-element-5f43b6d2\" data-id=\"5f43b6d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-554f923 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Black-gray 7021&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"554f923\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-554f923\" class=\"jet-tooltip-widget__content\"><p><strong>Black-gray 7021<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Czarno-szary-RAL7021.png\" class=\"attachment-large size-large wp-image-8809\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Czarno-szary-RAL7021.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Czarno-szary-RAL7021-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-1964dc3 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Bleached oak&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"1964dc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-1964dc3\" class=\"jet-tooltip-widget__content\"><p><strong>Bleached oak<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"741\" height=\"741\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/da-bielony-3.jpg\" class=\"attachment-large size-large wp-image-7022\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/da-bielony-3.jpg 741w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/da-bielony-3-300x300.jpg 300w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/da-bielony-3-150x150.jpg 150w\" sizes=\"(max-width: 741px) 100vw, 741px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-e2c6799 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Pure white&lt;br \\\/&gt;9010&lt;br \\\/&gt;&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"e2c6799\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-e2c6799\" class=\"jet-tooltip-widget__content\"><p><strong>Pure white<br \/>9010<br \/><\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"742\" height=\"742\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2025\/01\/Deko-RAL-9010-Art.-.13_23-915205-1.jpg\" class=\"attachment-large size-large wp-image-13514\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2025\/01\/Deko-RAL-9010-Art.-.13_23-915205-1.jpg 742w, https:\/\/avante.pl\/wp-content\/uploads\/2025\/01\/Deko-RAL-9010-Art.-.13_23-915205-1-300x300.jpg 300w, https:\/\/avante.pl\/wp-content\/uploads\/2025\/01\/Deko-RAL-9010-Art.-.13_23-915205-1-150x150.jpg 150w, https:\/\/avante.pl\/wp-content\/uploads\/2025\/01\/Deko-RAL-9010-Art.-.13_23-915205-1-100x100.jpg 100w\" sizes=\"(max-width: 742px) 100vw, 742px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-26eac66 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Brilliant white 9003&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"26eac66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-26eac66\" class=\"jet-tooltip-widget__content\"><p><strong>Brilliant white 9003<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Brylantowa-biel-RAL9003.png\" class=\"attachment-large size-large wp-image-8797\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Brylantowa-biel-RAL9003.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Brylantowa-biel-RAL9003-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-983015e elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;b&gt;Brushed brass&lt;\\\/b&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"983015e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-983015e\" class=\"jet-tooltip-widget__content\"><p><b>Brushed brass<\/b><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Mosiadz-szczotkowany.png\" class=\"attachment-large size-large wp-image-8881\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Mosiadz-szczotkowany.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Mosiadz-szczotkowany-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-10 elementor-top-column elementor-element elementor-element-746fdbf7\" data-id=\"746fdbf7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-4d4f985 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Realwood&lt;\\\/strong&gt;&lt;\\\/p&gt;&lt;p&gt;&lt;strong&gt;Scandinavian oak&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"4d4f985\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-4d4f985\" class=\"jet-tooltip-widget__content\"><p><strong>Realwood<\/strong><\/p><p><strong>Scandinavian oak<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"267\" height=\"267\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Realwood-dab-skandynawski-e1687547190266.png\" class=\"attachment-large size-large wp-image-8909\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Realwood-dab-skandynawski-e1687547190266.png 267w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Realwood-dab-skandynawski-e1687547190266-150x150.png 150w\" sizes=\"(max-width: 267px) 100vw, 267px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-2d150407 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;AnTeak&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"2d150407\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-2d150407\" class=\"jet-tooltip-widget__content\"><p><strong>AnTeak<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/AnTeak.png\" class=\"attachment-large size-large wp-image-8678\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/AnTeak.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/AnTeak-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-2a0fb12 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Cream 9001 matte&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"2a0fb12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-2a0fb12\" class=\"jet-tooltip-widget__content\"><p><strong>Cream 9001 matte<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Kremowy-RAL9001-matowy.png\" class=\"attachment-large size-large wp-image-8865\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Kremowy-RAL9001-matowy.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Kremowy-RAL9001-matowy-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-792004f elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Cream 9001&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"792004f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-792004f\" class=\"jet-tooltip-widget__content\"><p><strong>Cream 9001<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Kremowy-RAL9001.png\" class=\"attachment-large size-large wp-image-8869\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Kremowy-RAL9001.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Kremowy-RAL9001-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-528dd50 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Black-brown&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"528dd50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-528dd50\" class=\"jet-tooltip-widget__content\"><p><strong>Black-brown<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2025\/01\/czarno-brazowy-851805-v2.jpg\" class=\"attachment-large size-large wp-image-13522\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2025\/01\/czarno-brazowy-851805-v2.jpg 200w, https:\/\/avante.pl\/wp-content\/uploads\/2025\/01\/czarno-brazowy-851805-v2-150x150.jpg 150w, https:\/\/avante.pl\/wp-content\/uploads\/2025\/01\/czarno-brazowy-851805-v2-100x100.jpg 100w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-10 elementor-top-column elementor-element elementor-element-ed8be7e\" data-id=\"ed8be7e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-fbaee74 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Realwood&lt;\\\/strong&gt;&lt;\\\/p&gt;&lt;p&gt;&lt;strong&gt;Anthracite 7016&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"fbaee74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-fbaee74\" class=\"jet-tooltip-widget__content\"><p><strong>Realwood<\/strong><\/p><p><strong>Anthracite 7016<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Realwood-Antracyt-RAL-7016.png\" class=\"attachment-large size-large wp-image-8897\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Realwood-Antracyt-RAL-7016.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Realwood-Antracyt-RAL-7016-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-15deadcb elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Light oak&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"15deadcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-15deadcb\" class=\"jet-tooltip-widget__content\"><p><strong>Light oak<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/jasny_dab.png\" class=\"attachment-large size-large wp-image-8694\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/jasny_dab.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/jasny_dab-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-b03a2d9 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Pure white 9010&lt;\\\/strong&gt;&lt;\\\/p&gt;&lt;p&gt;&lt;strong&gt;matt&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"b03a2d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-b03a2d9\" class=\"jet-tooltip-widget__content\"><p><strong>Pure white 9010<\/strong><\/p><p><strong>matt<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Czysty-bialy-RAL9010-matowy.png\" class=\"attachment-large size-large wp-image-8833\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Czysty-bialy-RAL9010-matowy.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Czysty-bialy-RAL9010-matowy-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-54cd2b6 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;b&gt;Navy blue 5011&lt;\\\/b&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"54cd2b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-54cd2b6\" class=\"jet-tooltip-widget__content\"><p><b>Navy blue 5011<\/b><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Granatowy-RAL5011.png\" class=\"attachment-large size-large wp-image-8857\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Granatowy-RAL5011.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Granatowy-RAL5011-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-9c2453d elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Oregon&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"9c2453d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-9c2453d\" class=\"jet-tooltip-widget__content\"><p><strong>Oregon<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/oregon.png\" class=\"attachment-large size-large wp-image-8698\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/oregon.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/oregon-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-10 elementor-top-column elementor-element elementor-element-4afd70b5\" data-id=\"4afd70b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-5f8edd72 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Anthracite 7016&lt;\\\/strong&gt;&lt;\\\/p&gt;&lt;p&gt;&lt;strong&gt;structural&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"5f8edd72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-5f8edd72\" class=\"jet-tooltip-widget__content\"><p><strong>Anthracite 7016<\/strong><\/p><p><strong>structural<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/antracyt-RAL_7016-strukturalny.png\" class=\"attachment-large size-large wp-image-8626\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/antracyt-RAL_7016-strukturalny.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/antracyt-RAL_7016-strukturalny-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-2318cb12 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Mountain pine&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"2318cb12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-2318cb12\" class=\"jet-tooltip-widget__content\"><p><strong>Mountain pine<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/sosna-gorska.png\" class=\"attachment-large size-large wp-image-8710\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/sosna-gorska.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/sosna-gorska-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-6c8006c4 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Mahogany&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"6c8006c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-6c8006c4\" class=\"jet-tooltip-widget__content\"><p><strong>Mahogany<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/mahon.png\" class=\"attachment-large size-large wp-image-8634\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/mahon.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/mahon-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-3009eaf0 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Swamp oak&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"3009eaf0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-3009eaf0\" class=\"jet-tooltip-widget__content\"><p><strong>Swamp oak<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/dab_bagienny.png\" class=\"attachment-large size-large wp-image-8686\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/dab_bagienny.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/dab_bagienny-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-670d0203 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Dark oak&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"670d0203\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-670d0203\" class=\"jet-tooltip-widget__content\"><p><strong>Dark oak<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/dab-ciemny.png\" class=\"attachment-large size-large wp-image-8690\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/dab-ciemny.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/dab-ciemny-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-10 elementor-top-column elementor-element elementor-element-45538efd\" data-id=\"45538efd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-be11026 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Alux DB 703&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"be11026\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-be11026\" class=\"jet-tooltip-widget__content\"><p><strong>Alux DB 703<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/aluxDB703-1.png\" class=\"attachment-large size-large wp-image-7020\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/aluxDB703-1.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/aluxDB703-1-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-2d532ec elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Gray quartz&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"2d532ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-2d532ec\" class=\"jet-tooltip-widget__content\"><p><strong>Gray quartz<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/szary-kwarc.png\" class=\"attachment-large size-large wp-image-8949\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/szary-kwarc.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/szary-kwarc-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-d4b7acb elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Basalt grey 7012&lt;\\\/strong&gt;&lt;\\\/p&gt;&lt;p&gt;&lt;strong&gt;smooth&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"d4b7acb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-d4b7acb\" class=\"jet-tooltip-widget__content\"><p><strong>Basalt grey 7012<\/strong><\/p><p><strong>smooth<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Szary-bazaltowy-RAL7012-gladki.png\" class=\"attachment-large size-large wp-image-8929\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Szary-bazaltowy-RAL7012-gladki.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Szary-bazaltowy-RAL7012-gladki-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-1480ce63 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Walnut&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"1480ce63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-1480ce63\" class=\"jet-tooltip-widget__content\"><p><strong>Walnut<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/orzech-wloski.png\" class=\"attachment-large size-large wp-image-8638\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/orzech-wloski.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/orzech-wloski-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-6e32cf5 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Red 3011&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"6e32cf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-6e32cf5\" class=\"jet-tooltip-widget__content\"><p><strong>Red 3011<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Czerwony-RAL3011.png\" class=\"attachment-large size-large wp-image-8825\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Czerwony-RAL3011.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Czerwony-RAL3011-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-10 elementor-top-column elementor-element elementor-element-7cc814bf\" data-id=\"7cc814bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-1d3f472 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Brushed silver&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"1d3f472\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-1d3f472\" class=\"jet-tooltip-widget__content\"><p><strong>Brushed silver<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/srebrny-szczotkowany.png\" class=\"attachment-large size-large wp-image-8925\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/srebrny-szczotkowany.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/srebrny-szczotkowany-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-2d080e9 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;b&gt;Gray quartz 7039&lt;\\\/b&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"2d080e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-2d080e9\" class=\"jet-tooltip-widget__content\"><p><b>Gray quartz 7039<\/b><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Szary-kwarc-RAL7039-str.png\" class=\"attachment-large size-large wp-image-8945\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Szary-kwarc-RAL7039-str.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Szary-kwarc-RAL7039-str-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-f8eeab2 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Macore meranti&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"f8eeab2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-f8eeab2\" class=\"jet-tooltip-widget__content\"><p><strong>Macore meranti<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/MacoreMeranti.png\" class=\"attachment-large size-large wp-image-8873\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/MacoreMeranti.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/MacoreMeranti-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-87f3596 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Red 3005&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"87f3596\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-87f3596\" class=\"jet-tooltip-widget__content\"><p><strong>Red 3005<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Czerwony-RAL3005.png\" class=\"attachment-large size-large wp-image-8821\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Czerwony-RAL3005.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Czerwony-RAL3005-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-10 elementor-top-column elementor-element elementor-element-2f47b35f\" data-id=\"2f47b35f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-7f45fb9a elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Silver 7001&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"7f45fb9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-7f45fb9a\" class=\"jet-tooltip-widget__content\"><p><strong>Silver 7001<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/srebrny-RAL-7001.png\" class=\"attachment-large size-large wp-image-8921\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/srebrny-RAL-7001.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/srebrny-RAL-7001-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-324484a elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Grey concrete 7023&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"324484a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-324484a\" class=\"jet-tooltip-widget__content\"><p><strong>Grey concrete 7023<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Szary-beton-RAL7023.png\" class=\"attachment-large size-large wp-image-8937\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Szary-beton-RAL7023.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Szary-beton-RAL7023-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-7de079a elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Green 6009&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"7de079a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-7de079a\" class=\"jet-tooltip-widget__content\"><p><strong>Green 6009<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"741\" height=\"742\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/zielony_RAL6009_K.jpg\" class=\"attachment-large size-large wp-image-7019\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/zielony_RAL6009_K.jpg 741w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/zielony_RAL6009_K-300x300.jpg 300w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/zielony_RAL6009_K-150x150.jpg 150w\" sizes=\"(max-width: 741px) 100vw, 741px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-e041c0d elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;b&gt;Green 6005&lt;\\\/b&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"e041c0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-e041c0d\" class=\"jet-tooltip-widget__content\"><p><b>Green 6005<\/b><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"741\" height=\"742\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/zielony_RAL6005_K.jpg\" class=\"attachment-large size-large wp-image-7018\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/zielony_RAL6005_K.jpg 741w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/zielony_RAL6005_K-300x300.jpg 300w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/zielony_RAL6005_K-150x150.jpg 150w\" sizes=\"(max-width: 741px) 100vw, 741px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-10 elementor-top-column elementor-element elementor-element-37638ccf\" data-id=\"37638ccf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-f95058b elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Light grey 7035&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"f95058b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-f95058b\" class=\"jet-tooltip-widget__content\"><p><strong>Light grey 7035<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Szary-jasny-RAL7035.png\" class=\"attachment-large size-large wp-image-8941\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Szary-jasny-RAL7035.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Szary-jasny-RAL7035-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-3fc48cd8 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Wichester XA&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"3fc48cd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-3fc48cd8\" class=\"jet-tooltip-widget__content\"><p><strong>Wichester XA<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/winchester-cx.png\" class=\"attachment-large size-large wp-image-8654\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/winchester-cx.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/winchester-cx-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-6a6fb16f elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Walnuss&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"6a6fb16f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-6a6fb16f\" class=\"jet-tooltip-widget__content\"><p><strong>Walnuss<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/orzech.png\" class=\"attachment-large size-large wp-image-8702\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/orzech.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/orzech-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-6cca0f2 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Golden oak&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"6cca0f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-6cca0f2\" class=\"jet-tooltip-widget__content\"><p><strong>Golden oak<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"268\" height=\"268\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Zloty-Dab-e1687550217490.jpg\" class=\"attachment-large size-large wp-image-8965\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Zloty-Dab-e1687550217490.jpg 268w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/Zloty-Dab-e1687550217490-150x150.jpg 150w\" sizes=\"(max-width: 268px) 100vw, 268px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-10 elementor-top-column elementor-element elementor-element-53b3945b\" data-id=\"53b3945b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-4313b7f elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Basaltgrau&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"4313b7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-4313b7f\" class=\"jet-tooltip-widget__content\"><p><strong>Basaltgrau<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/szary-bazaltowy.png\" class=\"attachment-large size-large wp-image-8933\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/szary-bazaltowy.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/szary-bazaltowy-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-26c4c6cb elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Rustikale Eiche&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"26c4c6cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-26c4c6cb\" class=\"jet-tooltip-widget__content\"><p><strong>Rustikale Eiche<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/dab_rustykalny.png\" class=\"attachment-large size-large wp-image-8682\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/dab_rustykalny.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/05\/dab_rustykalny-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-153d48e9 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Schokoladenbraun&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"153d48e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-153d48e9\" class=\"jet-tooltip-widget__content\"><p><strong>Schokoladenbraun<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/czekoladowy-braz.png\" class=\"attachment-large size-large wp-image-8817\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/czekoladowy-braz.png 200w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/czekoladowy-braz-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-f73dee6 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;&lt;p&gt;&lt;strong&gt;Sommer Douglasie&lt;\\\/strong&gt;&lt;\\\/p&gt;&quot;,&quot;tooltipPlacement&quot;:&quot;bottom&quot;,&quot;tooltipArrow&quot;:false,&quot;xOffset&quot;:0,&quot;yOffset&quot;:0,&quot;tooltipAnimation&quot;:&quot;scale&quot;,&quot;tooltipTrigger&quot;:&quot;click&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;,&quot;tooltipDevices&quot;:[]}\" data-id=\"f73dee6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-f73dee6\" class=\"jet-tooltip-widget__content\"><p><strong>Sommer Douglasie<\/strong><\/p><\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"742\" height=\"742\" src=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/daglezja-letnia_K.jpg\" class=\"attachment-large size-large wp-image-7015\" alt=\"\" srcset=\"https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/daglezja-letnia_K.jpg 742w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/daglezja-letnia_K-300x300.jpg 300w, https:\/\/avante.pl\/wp-content\/uploads\/2023\/06\/daglezja-letnia_K-150x150.jpg 150w\" sizes=\"(max-width: 742px) 100vw, 742px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e42afd elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"2e42afd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-59e9a6a\" data-id=\"59e9a6a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c810dd6 elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"6c810dd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/avante.pl\/en\/accessories\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">see also accessories<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1356adc\" data-id=\"1356adc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d264d5 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"6d264d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/avante.pl\/category\/okna-pvc\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-left\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">All PVC windows<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f49077c elementor-section-height-min-height elementor-section-full_width elementor-section-height-default elementor-section-items-middle\" data-id=\"1f49077c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e021c9\" data-id=\"1e021c9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12638170 elementor-widget elementor-widget-heading\" data-id=\"12638170\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">we look forward to your questions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-372b7321 elementor-hidden-mobile_extra elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"372b7321\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Call us: +48 55 888 0 222<br>or write a message using the form<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16fb462d elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-laptop elementor-widget elementor-widget-text-editor\" data-id=\"16fb462d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Call us: +48 55 888 0 222<br>or write a message using the form<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39fbed9c elementor-align-left elementor-mobile-align-left elementor-widget elementor-widget-global elementor-global-7047 elementor-global-286 elementor-widget-button\" data-id=\"39fbed9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/avante.pl\/en\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">contact form<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Beautiful line, excellent thermal and acoustic insulation.<\/p>\n","protected":false},"author":5,"featured_media":13299,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-12491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pvc-windows"],"_links":{"self":[{"href":"https:\/\/avante.pl\/en\/wp-json\/wp\/v2\/posts\/12491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avante.pl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/avante.pl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/avante.pl\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/avante.pl\/en\/wp-json\/wp\/v2\/comments?post=12491"}],"version-history":[{"count":3,"href":"https:\/\/avante.pl\/en\/wp-json\/wp\/v2\/posts\/12491\/revisions"}],"predecessor-version":[{"id":14708,"href":"https:\/\/avante.pl\/en\/wp-json\/wp\/v2\/posts\/12491\/revisions\/14708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avante.pl\/en\/wp-json\/wp\/v2\/media\/13299"}],"wp:attachment":[{"href":"https:\/\/avante.pl\/en\/wp-json\/wp\/v2\/media?parent=12491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/avante.pl\/en\/wp-json\/wp\/v2\/categories?post=12491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/avante.pl\/en\/wp-json\/wp\/v2\/tags?post=12491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}